{"id":12586,"date":"2021-05-24T15:30:07","date_gmt":"2021-05-24T13:30:07","guid":{"rendered":"https:\/\/www.hydrotab.gr\/?page_id=12586"},"modified":"2025-12-05T11:35:28","modified_gmt":"2025-12-05T09:35:28","slug":"bt-series","status":"publish","type":"page","link":"https:\/\/www.hydrotab.gr\/el\/bt-series\/","title":{"rendered":"\u03a3\u03b5\u03b9\u03c1\u03ac \u03a6\u03bb\u03b1\u03c0\u03c2  BT"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12586\" class=\"elementor elementor-12586\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee8617d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee8617d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ea4fab\" data-id=\"4ea4fab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bead523 elementor-widget elementor-widget-heading\" data-id=\"bead523\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The BT Series Interceptors<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ecbd8b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9ecbd8b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:14704,&quot;url&quot;:&quot;https:\\\/\\\/www.hydrotab.gr\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/BT3.png&quot;},{&quot;id&quot;:12947,&quot;url&quot;:&quot;https:\\\/\\\/www.hydrotab.gr\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/MicrosoftTeams-image-7-2.jpg&quot;},{&quot;id&quot;:12764,&quot;url&quot;:&quot;https:\\\/\\\/www.hydrotab.gr\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/bt-on-boat.jpg&quot;},{&quot;id&quot;:12765,&quot;url&quot;:&quot;https:\\\/\\\/www.hydrotab.gr\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/BT-and-controllers.jpg&quot;},{&quot;id&quot;:12938,&quot;url&quot;:&quot;https:\\\/\\\/www.hydrotab.gr\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/BT-Still2-1.jpg&quot;}],&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7786172\" data-id=\"7786172\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa93668 elementor-widget elementor-widget-spacer\" data-id=\"aa93668\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-327094e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"327094e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-231a7df\" data-id=\"231a7df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d26ed3 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"8d26ed3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_opacity_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:27,&quot;end&quot;:73}},&quot;motion_fx_opacity_effect&quot;:&quot;yes&quot;,&quot;motion_fx_opacity_direction&quot;:&quot;in-out&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;motion_fx_opacity_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The BT Series is the compact Inox-316 series of Hydrotab. Its T-Shape design provides excellent and efficient operation and its 6 different standard models make sure that they fit in hulls of any size!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9078733 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9078733\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7d59ebe\" data-id=\"7d59ebe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c6e6f4 elementor-widget elementor-widget-image\" data-id=\"4c6e6f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateX_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:39}},&quot;motion_fx_blur_effect&quot;:&quot;yes&quot;,&quot;motion_fx_blur_direction&quot;:&quot;out-in-out&quot;,&quot;motion_fx_blur_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:14,&quot;sizes&quot;:[]},&quot;motion_fx_blur_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:29,&quot;end&quot;:73}},&quot;motion_fx_translateX_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-Still2.jpg\" class=\"attachment-full size-full wp-image-12843\" alt=\"\" srcset=\"https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-Still2.jpg 1080w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-Still2-300x300.jpg 300w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-Still2-1024x1024.jpg 1024w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-Still2-150x150.jpg 150w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-Still2-768x768.jpg 768w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-Still2-12x12.jpg 12w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-Still2-600x600.jpg 600w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-Still2-100x100.jpg 100w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a181e72\" data-id=\"a181e72\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:50}},&quot;motion_fx_blur_effect&quot;:&quot;yes&quot;,&quot;motion_fx_blur_direction&quot;:&quot;out-in-out&quot;,&quot;motion_fx_blur_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:41,&quot;end&quot;:75}},&quot;motion_fx_translateX_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_blur_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:7,&quot;sizes&quot;:[]},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile_extra&quot;,&quot;mobile&quot;]}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38fd47b elementor-widget elementor-widget-heading\" data-id=\"38fd47b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Robust design<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d164995 elementor-widget elementor-widget-text-editor\" data-id=\"d164995\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The BT interceptors have an Inox-316 body, which allows them to withstand the high forces of the open sea. Its simple design principle ensures that it never fails, even in the harshest sea conditions and -at the same time- provides a very simple installation process.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb0297e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"fb0297e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/youtu.be\\\/nFfS7_Ry28s&quot;,&quot;background_video_start&quot;:32,&quot;background_video_end&quot;:40,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\" role=\"presentation\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b9c82fb\" data-id=\"b9c82fb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b91583f elementor-widget elementor-widget-heading\" data-id=\"b91583f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Revolutionary Pneumatic\nTechnology<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4caa369 elementor-widget elementor-widget-text-editor\" data-id=\"4caa369\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The BT Series operates using Hydrotab&#8217;s revolutionary patented technology. The motion of the interceptor is controlled by a high resistance bladder which is expanded pneumatically. This simple idea allows us to have a simple and open-to-the-sea-water mechanism without any need of sealing or use of any sensitive to sea-water parts (gears, shafts, electronic elements, motors, etc), making the interceptors indestructible!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0130e1e elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"0130e1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;underline&quot;,&quot;highlighted_text&quot;:&quot;Patented&quot;,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;highlight_animation_duration&quot;:1200}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 class=\"elementor-headline\">\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">Patented<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7ec4366 elementor-invisible\" data-id=\"7ec4366\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68ad0bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68ad0bc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec32546 elementor-invisible\" data-id=\"ec32546\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2586eb4 elementor-widget elementor-widget-heading\" data-id=\"2586eb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Size versatility<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11f11a2 elementor-widget elementor-widget-text-editor\" data-id=\"11f11a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hydrotab&#8217;s technology ensures massive shifting forces (up to 3500 kg!) that scale up as the size of the bladder increases. This allows the BT series to be made in any size &#8211; from 20cm all the way to 2m in length!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-271d486 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"271d486\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f55fbbb\" data-id=\"f55fbbb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f11804e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f11804e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=1dXxsYcQnmY&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\" role=\"presentation\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-705b49e\" data-id=\"705b49e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd39d74 elementor-widget elementor-widget-spacer\" data-id=\"dd39d74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cde1bf4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cde1bf4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0a76ed6\" data-id=\"0a76ed6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a675c0c elementor-widget elementor-widget-spacer\" data-id=\"a675c0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c33137 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c33137\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-680ee18\" data-id=\"680ee18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-edb28b7 elementor-widget elementor-widget-heading\" data-id=\"edb28b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Environmentally friendly design<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb5a22c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb5a22c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dcd3060\" data-id=\"dcd3060\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89b977d elementor-align-center elementor-widget elementor-widget-lottie\" data-id=\"89b977d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;source_json&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.hydrotab.gr\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/lf30_editor_szr84umw.json&quot;,&quot;id&quot;:11836,&quot;size&quot;:&quot;&quot;},&quot;source&quot;:&quot;media_file&quot;,&quot;caption_source&quot;:&quot;none&quot;,&quot;link_to&quot;:&quot;none&quot;,&quot;trigger&quot;:&quot;arriving_to_viewport&quot;,&quot;viewport&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;play_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;end_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;renderer&quot;:&quot;svg&quot;}\" data-widget_type=\"lottie.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-lottie__container\"><div class=\"e-lottie__animation\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a419dfe elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"a419dfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The interceptors are constructed with easily recyclable materials, reducing waste and the carbon footprint of their production!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6ee3508\" data-id=\"6ee3508\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e16aea5 elementor-align-center elementor-widget elementor-widget-lottie\" data-id=\"e16aea5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;source_json&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/www.hydrotab.gr\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/lf30_editor_dblonwgc.json&quot;,&quot;id&quot;:11837,&quot;size&quot;:&quot;&quot;},&quot;source&quot;:&quot;media_file&quot;,&quot;caption_source&quot;:&quot;none&quot;,&quot;link_to&quot;:&quot;none&quot;,&quot;trigger&quot;:&quot;arriving_to_viewport&quot;,&quot;viewport&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;play_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;end_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;renderer&quot;:&quot;svg&quot;}\" data-widget_type=\"lottie.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-lottie__container\"><div class=\"e-lottie__animation\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-166e053 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"166e053\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The pneumatic operation works using compressed air instead of hydraulic oils, ensuring no pollution of the marine environment!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2808ecd elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"2808ecd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9f02043\" data-id=\"9f02043\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec076cb elementor-widget elementor-widget-text-editor\" data-id=\"ec076cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>BT offers 6 standard models of interceptors, but can be customized ordered to be up to 2m in length<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-226129c elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"226129c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">160BT<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ad5c36 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7ad5c36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">320BT<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b13df8 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9b13df8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">480BT<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55fca56 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"55fca56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">640BT<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0c67a7 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f0c67a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">800BT<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b4f811 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2b4f811\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">960BT<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e4472e5\" data-id=\"e4472e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9de315a elementor-widget elementor-widget-image\" data-id=\"9de315a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1600\" height=\"999\" src=\"https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-sizes.jpg\" class=\"attachment-full size-full wp-image-12760\" alt=\"\" srcset=\"https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-sizes.jpg 1600w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-sizes-300x187.jpg 300w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-sizes-1024x639.jpg 1024w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-sizes-768x480.jpg 768w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-sizes-1536x959.jpg 1536w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-sizes-16x10.jpg 16w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-sizes-600x375.jpg 600w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4cae87f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4cae87f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c1bf378\" data-id=\"c1bf378\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65f04dd elementor-widget elementor-widget-text-editor\" data-id=\"65f04dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><div id=\"footable_parent_7602\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent semantic_ui \">\n                <table data-ninja_table_instance=\"ninja_table_instance_0\" data-footable_id=\"7602\" data-filter-delay=\"1000\" aria-label=\"bt-series.csv\"            id=\"footable_7602\"\n           data-unique_identifier=\"ninja_table_unique_id_591962736_7602\"\n           class=\" foo-table ninja_footable foo_table_7602 ninja_table_unique_id_591962736_7602 ui table  ninja_search_right nt_type_legacy_table selectable striped vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                    <\/colgroup>\n        <thead>\n<tr class=\"footable-header\">\n                                                                                                        <th scope=\"col\"  class=\"ninja_column_0 ninja_clmn_nm_srseries \">BT Series<\/th><th scope=\"col\"  class=\"ninja_column_1 ninja_clmn_nm_lengthmm \">Length (mm)<\/th><th scope=\"col\"  class=\"ninja_column_2 ninja_clmn_nm_widthmm \">Width (mm)<\/th><th scope=\"col\"  class=\"ninja_column_3 ninja_clmn_nm_heightmm \">Height with fitting (mm)<\/th><th scope=\"col\"  class=\"ninja_column_4 ninja_clmn_nm_height_without_fitting_mm \">Height without fitting (mm)<\/th><th scope=\"col\"  class=\"ninja_column_5 ninja_clmn_nm_maxdeploymentstrokemm \">Max Deployment (Stroke) (mm)<\/th><\/tr>\n<\/thead>\n<tbody>\n\n        <tr data-row_id=\"109\" class=\"ninja_table_row_0 nt_row_id_109\">\n            <td>160BT<\/td><td>210<\/td><td>89<\/td><td>115,5<\/td><td>90,5<\/td><td>35<\/td>        <\/tr>\n            <tr data-row_id=\"112\" class=\"ninja_table_row_1 nt_row_id_112\">\n            <td>320BT<\/td><td>370<\/td><td>89<\/td><td>115,5<\/td><td>90,5<\/td><td>35<\/td>        <\/tr>\n            <tr data-row_id=\"113\" class=\"ninja_table_row_2 nt_row_id_113\">\n            <td>480BT<\/td><td>545<\/td><td>89<\/td><td>115,5<\/td><td>90,5<\/td><td>35<\/td>        <\/tr>\n            <tr data-row_id=\"114\" class=\"ninja_table_row_3 nt_row_id_114\">\n            <td>640BT<\/td><td>700<\/td><td>89<\/td><td>115,5<\/td><td>90,5<\/td><td>35<\/td>        <\/tr>\n            <tr data-row_id=\"115\" class=\"ninja_table_row_4 nt_row_id_115\">\n            <td>800BT<\/td><td>870<\/td><td>89<\/td><td>115,5<\/td><td>90,5<\/td><td>35<\/td>        <\/tr>\n            <tr data-row_id=\"116\" class=\"ninja_table_row_5 nt_row_id_116\">\n            <td>960BT<\/td><td>1030<\/td><td>89<\/td><td>115,5<\/td><td>90,5<\/td><td>35<\/td>        <\/tr>\n    <\/tbody><!--ninja_tobody_rendering_done-->\n    <\/table>\n    \n    \n    \n<\/div>\n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b793502\" data-id=\"b793502\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e6c673 elementor-widget elementor-widget-image\" data-id=\"4e6c673\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"223\" src=\"https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/10\/BT-INTERCEPTORS-OVERALL-DIMENSIONS-1-1024x285.png\" class=\"attachment-large size-large wp-image-14752\" alt=\"\" srcset=\"https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/10\/BT-INTERCEPTORS-OVERALL-DIMENSIONS-1-1024x285.png 1024w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/10\/BT-INTERCEPTORS-OVERALL-DIMENSIONS-1-300x84.png 300w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/10\/BT-INTERCEPTORS-OVERALL-DIMENSIONS-1-768x214.png 768w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/10\/BT-INTERCEPTORS-OVERALL-DIMENSIONS-1-1536x428.png 1536w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/10\/BT-INTERCEPTORS-OVERALL-DIMENSIONS-1-18x5.png 18w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/10\/BT-INTERCEPTORS-OVERALL-DIMENSIONS-1-600x167.png 600w, https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/10\/BT-INTERCEPTORS-OVERALL-DIMENSIONS-1.png 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d2025de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d2025de\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8d59743\" data-id=\"8d59743\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28c296e elementor-widget elementor-widget-heading\" data-id=\"28c296e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Usefull files<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07df294 eael-table-align-center eael-dt-th-align-left elementor-widget elementor-widget-eael-data-table\" data-id=\"07df294\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-data-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"eael-data-table-wrap\" data-table_id=\"07df294\" id=\"eael-data-table-wrapper-07df294\" data-custom_responsive=\"false\">\n\t\t\t<table class=\"tablesorter eael-data-table center\" id=\"eael-data-table-07df294\">\n\t\t\t    <thead>\n\t\t\t        <tr class=\"table-header\">\n\t\t\t\t\t\t\t\t\t            <th class=\"\" id=\"\" colspan=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"data-table-header-text\">Table Header<\/span><\/th>\n\t\t\t        \t\t\t\t        <\/tr>\n\t\t\t    <\/thead>\n\t\t\t  \t<tbody>\n\t\t\t\t\t\t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><strong>Drilling patterns<\/strong><\/p>\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hydrotab.gr\/download\/24\/drilling-patterns\/636\/drilling-pattern-bt-series-960bt.pdf\">960BT<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hydrotab.gr\/download\/24\/drilling-patterns\/635\/drilling-pattern-bt-series-800bt.pdf\">800BT<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hydrotab.gr\/download\/24\/drilling-patterns\/633\/drilling-pattern-bt-series-640bt.pdf\">640BT<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hydrotab.gr\/download\/24\/drilling-patterns\/634\/drilling-pattern-bt-series-480bt.pdf\">480BT<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hydrotab.gr\/download\/24\/drilling-patterns\/639\/drilling-pattern-bt-series-320bt.pdf\">320BT<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hydrotab.gr\/download\/24\/drilling-patterns\/637\/drilling-pattern-bt-series-160bt.pdf\">160BT<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t        \t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p><strong>3D CAD files<\/strong><\/p>\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hydrotab.gr\/download\/22\/3d-cad-files\/624\/interceptor-960bt-asm-00564.igs\">960BT<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hydrotab.gr\/download\/22\/3d-cad-files\/623\/interceptor-800bt-asm-00563.igs\">800BT<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hydrotab.gr\/download\/22\/3d-cad-files\/622\/interceptor-640bt-asm-00562.igs\">640BT<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hydrotab.gr\/download\/22\/3d-cad-files\/628\/interceptor-480bt-asm-00561.igs\">480BT<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hydrotab.gr\/download\/22\/3d-cad-files\/619\/interceptor-320bt-asm-00560.igs\">320BT<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hydrotab.gr\/download\/22\/3d-cad-files\/618\/interceptor-160bt-asm-00928.igs\">160BT<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t        \t\t\t    <\/tbody>\n\t\t\t<\/table>\n\t\t<\/div>\n\t  \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2963378 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2963378\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-90a8d38\" data-id=\"90a8d38\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7de429 elementor-widget elementor-widget-heading\" data-id=\"f7de429\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Manuals:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-99689bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"99689bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-174dd5b\" data-id=\"174dd5b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f551f0 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"0f551f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-grow\" href=\"https:\/\/www.hydrotab.gr\/download\/21\/user-manuals\/8462\/bt-series-nmea2000-moby-control-air-unit-ii-rev-c.pdf\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-file-pdf\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd7a158 elementor-widget elementor-widget-heading\" data-id=\"dd7a158\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">BT with automatic system<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-efe30e7\" data-id=\"efe30e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21ea7c2 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"21ea7c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-grow\" href=\"https:\/\/www.hydrotab.gr\/download\/21\/user-manuals\/7701\/bt-series-3dhc-controller-rev-l.pdf\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-file-pdf\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2caa5dc elementor-widget elementor-widget-heading\" data-id=\"2caa5dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">BT with manual system<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e6288ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e6288ca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation_mobile&quot;:&quot;slideInLeft&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1822edd\" data-id=\"1822edd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf51a26 elementor-widget elementor-widget-heading\" data-id=\"cf51a26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Check out our other series of Interceptors:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aecacd1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aecacd1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-9c98f77\" data-id=\"9c98f77\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e679f23 elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"e679f23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2022\/11\/Artboard-1-4.png);\" role=\"img\" aria-label=\"Artboard 1\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/www.hydrotab.gr\/ls-series\/\">\n\t\t\t\t\t\tLS Series\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-ribbon\">\n\t\t\t\t<div class=\"elementor-ribbon-inner\">\n\t\t\t\t\tNEW\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-dc5a373\" data-id=\"dc5a373\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7f3f98 elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"b7f3f98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/www.hydrotab.gr\/sr-series\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/10\/SR-SERIES-1024x435.png);\" role=\"img\" aria-label=\"SR-SERIES\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<span class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\tSR Series\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-ad08c78\" data-id=\"ad08c78\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea5179e elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"ea5179e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/10\/FW-SERIES-scaled-1-1024x435.png);\" role=\"img\" aria-label=\"FW-SERIES-scaled\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/www.hydrotab.gr\/fw-series\/\">\n\t\t\t\t\t\tFW Series\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-52cbba2\" data-id=\"52cbba2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12e0215 elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"12e0215\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/10\/TS-SERIES-scaled-1-1024x435.png);\" role=\"img\" aria-label=\"TS-SERIES-scaled\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\t   \t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/www.hydrotab.gr\/ts-series\/\">\n\t\t\t\t\t\tTS Series\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-2520e16\" data-id=\"2520e16\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e1ab0f elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"8e1ab0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/www.hydrotab.gr\/fx-series\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/10\/FW-SERIES-scaled-2-1024x435.webp);\" role=\"img\" aria-label=\"FW-SERIES-scaled-2\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\t   \t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<span class=\"elementor-cta__button elementor-button elementor-size-\">\n\t\t\t\t\t\tFX Series\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-ribbon\">\n\t\t\t\t<div class=\"elementor-ribbon-inner\">\n\t\t\t\t\tNEW\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d6d6c45 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d6d6c45\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a667432\" data-id=\"a667432\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e09589 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"3e09589\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">...or click here to visit the store.<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>The BT Series Interceptors The BT Series is the compact Inox-316 series of Hydrotab. Its T-Shape design provides excellent and efficient operation and its 6 different standard models make sure that they fit in hulls of any size! Robust design The BT interceptors have an Inox-316 body, which allows them to withstand the high forces [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_angie_page":false,"footnotes":""},"class_list":["post-12586","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>BT Series Interceptors - Hydrotab<\/title>\n<meta name=\"description\" content=\"Hydrotab&#039;s heavy duty BT Series Interceptors. Robust, efficient and reliable, the BT series can be custom made to lengths up to 2 meters!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hydrotab.gr\/el\/bt-series\/\" \/>\n<meta property=\"og:locale\" content=\"el_GR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BT Series\" \/>\n<meta property=\"og:description\" content=\"Hydrotab&#039;s heavy duty BT Series Interceptors. Robust, efficient and reliable, the BT series can be custom made to lengths up to 2 meters!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hydrotab.gr\/el\/bt-series\/\" \/>\n<meta property=\"og:site_name\" content=\"Hydrotab\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hydrotab\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-05T09:35:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-Still2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0395\u03ba\u03c4\u03b9\u03bc\u03ce\u03bc\u03b5\u03bd\u03bf\u03c2 \u03c7\u03c1\u03cc\u03bd\u03bf\u03c2 \u03b1\u03bd\u03ac\u03b3\u03bd\u03c9\u03c3\u03b7\u03c2\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 \u03bb\u03b5\u03c0\u03c4\u03ac\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hydrotab.gr\\\/bt-series\\\/\",\"url\":\"https:\\\/\\\/www.hydrotab.gr\\\/bt-series\\\/\",\"name\":\"BT Series Interceptors - Hydrotab\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hydrotab.gr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hydrotab.gr\\\/bt-series\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hydrotab.gr\\\/bt-series\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hydrotab.gr\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/BT-Still2.jpg\",\"datePublished\":\"2021-05-24T13:30:07+00:00\",\"dateModified\":\"2025-12-05T09:35:28+00:00\",\"description\":\"Hydrotab's heavy duty BT Series Interceptors. Robust, efficient and reliable, the BT series can be custom made to lengths up to 2 meters!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hydrotab.gr\\\/bt-series\\\/#breadcrumb\"},\"inLanguage\":\"el\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hydrotab.gr\\\/bt-series\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\\\/\\\/www.hydrotab.gr\\\/bt-series\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hydrotab.gr\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/BT-Still2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hydrotab.gr\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/BT-Still2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hydrotab.gr\\\/bt-series\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hydrotab.gr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BT Series\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hydrotab.gr\\\/#website\",\"url\":\"https:\\\/\\\/www.hydrotab.gr\\\/\",\"name\":\"Hydrotab\",\"description\":\"Trim Tab Interceptors\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hydrotab.gr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hydrotab.gr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"el\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hydrotab.gr\\\/#organization\",\"name\":\"Hydrotab\",\"url\":\"https:\\\/\\\/www.hydrotab.gr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\\\/\\\/www.hydrotab.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.hydrotab.gr\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/HTlogo.png?fit=230%2C124&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.hydrotab.gr\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/HTlogo.png?fit=230%2C124&ssl=1\",\"width\":230,\"height\":124,\"caption\":\"Hydrotab\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hydrotab.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hydrotab\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC77dWvsYHN5ARsRabftPR0A\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"BT Series Interceptors - Hydrotab","description":"Hydrotab's heavy duty BT Series Interceptors. Robust, efficient and reliable, the BT series can be custom made to lengths up to 2 meters!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hydrotab.gr\/el\/bt-series\/","og_locale":"el_GR","og_type":"article","og_title":"BT Series","og_description":"Hydrotab's heavy duty BT Series Interceptors. Robust, efficient and reliable, the BT series can be custom made to lengths up to 2 meters!","og_url":"https:\/\/www.hydrotab.gr\/el\/bt-series\/","og_site_name":"Hydrotab","article_publisher":"https:\/\/www.facebook.com\/hydrotab\/","article_modified_time":"2025-12-05T09:35:28+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-Still2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u0395\u03ba\u03c4\u03b9\u03bc\u03ce\u03bc\u03b5\u03bd\u03bf\u03c2 \u03c7\u03c1\u03cc\u03bd\u03bf\u03c2 \u03b1\u03bd\u03ac\u03b3\u03bd\u03c9\u03c3\u03b7\u03c2":"3 \u03bb\u03b5\u03c0\u03c4\u03ac"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hydrotab.gr\/bt-series\/","url":"https:\/\/www.hydrotab.gr\/bt-series\/","name":"BT Series Interceptors - Hydrotab","isPartOf":{"@id":"https:\/\/www.hydrotab.gr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hydrotab.gr\/bt-series\/#primaryimage"},"image":{"@id":"https:\/\/www.hydrotab.gr\/bt-series\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-Still2.jpg","datePublished":"2021-05-24T13:30:07+00:00","dateModified":"2025-12-05T09:35:28+00:00","description":"Hydrotab's heavy duty BT Series Interceptors. Robust, efficient and reliable, the BT series can be custom made to lengths up to 2 meters!","breadcrumb":{"@id":"https:\/\/www.hydrotab.gr\/bt-series\/#breadcrumb"},"inLanguage":"el","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hydrotab.gr\/bt-series\/"]}]},{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/www.hydrotab.gr\/bt-series\/#primaryimage","url":"https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-Still2.jpg","contentUrl":"https:\/\/www.hydrotab.gr\/wp-content\/uploads\/2021\/05\/BT-Still2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hydrotab.gr\/bt-series\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hydrotab.gr\/"},{"@type":"ListItem","position":2,"name":"BT Series"}]},{"@type":"WebSite","@id":"https:\/\/www.hydrotab.gr\/#website","url":"https:\/\/www.hydrotab.gr\/","name":"\u03a4\u03b1 Hydrotab","description":"\u039a\u03ac\u03b8\u03b5\u03c4\u03b1 \u03c6\u03bb\u03b1\u03c0\u03c2","publisher":{"@id":"https:\/\/www.hydrotab.gr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hydrotab.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"el"},{"@type":"Organization","@id":"https:\/\/www.hydrotab.gr\/#organization","name":"\u03a4\u03b1 Hydrotab","url":"https:\/\/www.hydrotab.gr\/","logo":{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/www.hydrotab.gr\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.hydrotab.gr\/wp-content\/uploads\/2019\/01\/HTlogo.png?fit=230%2C124&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.hydrotab.gr\/wp-content\/uploads\/2019\/01\/HTlogo.png?fit=230%2C124&ssl=1","width":230,"height":124,"caption":"Hydrotab"},"image":{"@id":"https:\/\/www.hydrotab.gr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hydrotab\/","https:\/\/www.youtube.com\/channel\/UC77dWvsYHN5ARsRabftPR0A"]}]}},"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Pantelis Filis","author_link":"https:\/\/www.hydrotab.gr\/el\/author\/design3olympicltd-gr\/"},"rttpg_comment":0,"rttpg_category":null,"rttpg_excerpt":"The BT Series Interceptors The BT Series is the compact Inox-316 series of Hydrotab. Its T-Shape design provides excellent and efficient operation and its 6 different standard models make sure that they fit in hulls of any size! Robust design The BT interceptors have an Inox-316 body, which allows them to withstand the high forces&hellip;","_links":{"self":[{"href":"https:\/\/www.hydrotab.gr\/el\/wp-json\/wp\/v2\/pages\/12586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hydrotab.gr\/el\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hydrotab.gr\/el\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hydrotab.gr\/el\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hydrotab.gr\/el\/wp-json\/wp\/v2\/comments?post=12586"}],"version-history":[{"count":170,"href":"https:\/\/www.hydrotab.gr\/el\/wp-json\/wp\/v2\/pages\/12586\/revisions"}],"predecessor-version":[{"id":20867,"href":"https:\/\/www.hydrotab.gr\/el\/wp-json\/wp\/v2\/pages\/12586\/revisions\/20867"}],"wp:attachment":[{"href":"https:\/\/www.hydrotab.gr\/el\/wp-json\/wp\/v2\/media?parent=12586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}